{"id":3337,"date":"2020-06-30T13:40:23","date_gmt":"2020-06-30T11:40:23","guid":{"rendered":"https:\/\/svnew.mailbox-marketing7.be\/product\/phonebox\/"},"modified":"2023-03-28T14:17:12","modified_gmt":"2023-03-28T12:17:12","slug":"phonebox","status":"publish","type":"producten","link":"https:\/\/www.sv.be\/fr\/produit\/phonebox\/","title":{"rendered":"PhoneBox"},"content":{"rendered":"\n<p>Le concept de la PhoneBox de PROOFF est n\u00e9 de l&#8217;observation des espaces et de leur utilisation. Public et priv\u00e9. Le PhoneBox permet aux utilisateurs de choisir un moment d&#8217;isolement. Le petit auvent att\u00e9nue le murmure \u00e0 l&#8217;int\u00e9rieur et coupe la conversation \u00e0 l&#8217;ext\u00e9rieur. Il en r\u00e9sulte un sentiment de confort et d&#8217;intimit\u00e9. Le design \u00e9l\u00e9gant d&#8217;AXIA Design est compact et s&#8217;adapte \u00e0 tout type d&#8217;espace.<\/p>\n","protected":false},"featured_media":3338,"menu_order":0,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"type-meubilair":[232],"project-toepassing":[87,72],"toepassingen":[109],"collecties":[79],"class_list":["post-3337","producten","type-producten","status-publish","has-post-thumbnail","hentry","type-meubilair-space-in-space-fr","project-toepassing-bibliotheque","project-toepassing-bureau","toepassingen-acoustique-confidentialite","collecties-prooff-fr"],"_links":{"self":[{"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/producten\/3337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/types\/producten"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/media\/3338"}],"wp:attachment":[{"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/media?parent=3337"}],"wp:term":[{"taxonomy":"type-meubilair","embeddable":true,"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/type-meubilair?post=3337"},{"taxonomy":"project-toepassing","embeddable":true,"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/project-toepassing?post=3337"},{"taxonomy":"toepassingen","embeddable":true,"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/toepassingen?post=3337"},{"taxonomy":"collecties","embeddable":true,"href":"https:\/\/www.sv.be\/fr\/wp-json\/wp\/v2\/collecties?post=3337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}